{"text_format":"1","workbook":"xlsx","n_sheets":5,"sheets":["TVN20 Calculator","Source","MODEL","BITRATE","proposed"],"not_rendered":{"charts":0,"images":1,"macros":1,"external_links":0,"defined_names":18,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"TVN20 Calculator","index":0,"n_rows":44,"n_cols":26,"rows_kept":44,"cut":false,"hidden":false,"merged":[[9,21,10,21],[12,20,13,20],[12,21,13,21],[26,0,26,7],[9,17,10,17],[12,17,13,17],[15,17,16,17],[9,20,10,20]]}
[null,null,null,"TruVision NVR 20"]
[null,null,null," Calculator"]
[]
[]
[]
[null,null,null,"UNIT TYPE","STORAGE CAPACITY (TB)",null,"DAYS of STORAGE"]
[null,null,null,null,null,null,{"$f":"IF(ISERROR(1/SUM(Q10:Q25)),\"0\", (1/SUM(Q10:Q25)))","v":"0"}]
[]
["Channel no.","Camera Name","Valid Config","Resolution","Frame Rate","Recommended  Bit Rate\n(kbps)","Custom Bit Rate(kbps)","% OF MOTION","Recording per day (TB)","Resolution","Bit Rate","Framerate","1080/UXGA","本通道路数","总路数","总接入路数"]
[1,null,{"$f":"IF(D$7=\"\",\"N\",IF(O10>P10,\"N\",\"Y\"))","v":"N"},null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D10,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E10,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D10,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E10,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,{"$f":"IF(C10=\"N\",0,(IF(ISERROR((IF(G10=\"\", IF(ISERROR(F10), 0, F10), G10)*3600*24/8)/(0.95*1024*1024*1024)*H10),\"0\", ((IF(G10=\"\", IF(ISERROR(F10), 0, F10), G10)*3600*24/8)/(0.95*1024*1024*1024)*H10))))","v":0},1,{"$f":"VALUE(IF(G10=\"\", IF(ISERROR(F10), 0, F10), G10))","v":0},{"$f":"VALUE(E10)","v":0},{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D10,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D10,Source!I:J,2,FALSE))","v":0},{"$f":"IF(K10<= 2048,1,IF(AND(K10 < 4097,K10 > 2048),2,4))","v":1},{"$f":"IF(M10>0,M10,N10)","v":1},{"$f":"IF($D$7=\"_8_Channel\",8,16)","v":16},{"$f":"(F10*3600*24/8)/($E$7*0.95*1024*1024*1024)*H10","v":{"$error":"#DIV/0!"}},"Total recording per day (TB)",null,null,"Total bandwidth used (Mbps)",{"$f":"(IF(G10=\"\",F10,G10)+IF(G11=\"\",F11,G11)+IF(G12=\"\",F12,G12)+IF(G13=\"\",F13,G13)+IF(G14=\"\",F14,G14)+IF(G15=\"\",F15,G15)+IF(G16=\"\",F16,G16)+IF(G17=\"\",F17,G17)+IF(G18=\"\",F18,G18)+IF(G19=\"\",F19,G19)+IF(G20=\"\",F20,G200)+IF(G21=\"\",F21,G21)+IF(G22=\"\",F22,G22)+IF(G23=\"\",F23,G23)+IF(G24=\"\",F24,G24)+IF(G25=\"\",F25,G25))/1024","v":0}]
[2,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D11,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E11,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D11,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E11,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,{"$f":"VALUE(IF(G11=\"\", IF(ISERROR(F11), 0, F11), G11))","v":0},{"$f":"VALUE(E11)","v":0},{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D11,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D11,Source!I:J,2,FALSE))","v":0},{"$f":"IF(K11<= 2048,1,IF(AND(K11 < 4097,K11 > 2048),2,4))","v":1},{"$f":"IF(M11>0,M11,N11)+O10","v":2},{"$f":"IF($D$7=\"_8_Channel\",8,16)","v":16},{"$f":"(F11*3600*24/8)/($E$7*0.95*1024*1024*1024)*H10","v":{"$error":"#DIV/0!"}},null,{"$f":"SUM($I$10:$I$25)","v":0}]
[3,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D12,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E12,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D12,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E12,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D12,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D12,Source!I:J,2,FALSE))","v":0},1,{"$f":"IF(M12>0,M12,N12)+O11","v":3},16,{"$error":"#DIV/0!"}]
[4,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D13,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E13,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D13,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E13,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D13,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D13,Source!I:J,2,FALSE))","v":0},1,4,16,{"$error":"#DIV/0!"},"Total recording per week (TB)",null,null,"Available bandwidth (Mbps)",{"$f":"IF(D7=\"_8_Channel\",16-V10,32-V10)","v":32}]
[5,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D14,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E14,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D14,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E14,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D14,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D14,Source!I:J,2,FALSE))","v":0},1,5,16,{"$error":"#DIV/0!"},null,{"$f":"S11*7","v":0}]
[6,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D15,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E15,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D15,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E15,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D15,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D15,Source!I:J,2,FALSE))","v":0},1,6,16,{"$error":"#DIV/0!"}]
[7,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D16,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E16,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D16,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E16,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D16,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D16,Source!I:J,2,FALSE))","v":0},1,7,16,{"$error":"#DIV/0!"},"Total recording per 30 days (TB)"]
[8,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D17,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E17,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D17,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E17,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D17,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D17,Source!I:J,2,FALSE))","v":0},1,8,16,{"$error":"#DIV/0!"},null,{"$f":"S11*30","v":0}]
[9,null,{"$f":"IF($D$7=\"\",\"N\",IF($D$7=\"_8_Channel\",\"N\",IF(O18>P18,\"N\",\"Y\")))","v":"N"},null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D18,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E18,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D18,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E18,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D18,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D18,Source!I:J,2,FALSE))","v":0},1,9,16,{"$error":"#DIV/0!"}]
[10,null,{"$f":"IF($D$7=\"\",\"N\",IF($D$7=\"_8_Channel\",\"N\",IF(O19>P19,\"N\",\"Y\")))","v":"N"},null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D19,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E19,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D19,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E19,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D19,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D19,Source!I:J,2,FALSE))","v":0},1,10,16,{"$error":"#DIV/0!"}]
[11,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D20,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E20,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D20,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E20,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D20,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D20,Source!I:J,2,FALSE))","v":0},1,11,16,{"$error":"#DIV/0!"}]
[12,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D21,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E21,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D21,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E21,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D21,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D21,Source!I:J,2,FALSE))","v":0},1,12,16,{"$error":"#DIV/0!"}]
[13,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D22,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E22,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D22,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E22,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D22,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D22,Source!I:J,2,FALSE))","v":0},1,13,16,{"$error":"#DIV/0!"}]
[14,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D23,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E23,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D23,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E23,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D23,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D23,Source!I:J,2,FALSE))","v":0},1,14,16,{"$error":"#DIV/0!"}]
[15,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D24,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E24,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D24,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E24,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D24,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D24,Source!I:J,2,FALSE))","v":0},1,15,16,{"$error":"#DIV/0!"}]
[16,null,"N",null,null,{"$f":"IF(ISERROR(INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D25,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E25,proposed!$C$2:$AB$2,0)+1)),\"0\",INDEX(proposed!$B$2:$AB$22,MATCH(SUBSTITUTE(D25,\" \",\"\"),proposed!$B$3:$B$22,0)+1,MATCH(E25,proposed!$C$2:$AB$2,0)+1))","v":"0"},null,1,0,1,0,0,{"$f":"IF(ISERROR(VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D25,Source!I:J,2,FALSE)),0,VLOOKUP('TVN20 Calculator'!#REF!&'TVN20 Calculator'!$D25,Source!I:J,2,FALSE))","v":0},1,16,16,{"$f":"(F24*3600*24/8)/($E$7*0.95*1024*1024*1024)*H24","v":{"$error":"#DIV/0!"}}]
[]
["This tool is to be used as a guideline to give you an estmation on storage required for the NVR to record the selected configuration in a good quality. The tool will let you deviate from the suggested value by the \"Custom bit rate\""]
[]
[null,"Mbps","Channels"]
[null,"< 2",1,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,1]
[null,"2 <> 4",2]
[null,"> 4",4]
[]
["Follow the 6 steps below"]
[]
["Step 1:",null,"Select an 8(SD) or a 16(SD) channel NVR"]
["Step 2:",null,"Select Hard Drive size in TB for the NVR"]
["Step 3:",null,"Select IP camera resolution"]
["Step 4:",null,"Select IP cameras Frame Rate"]
["Step 5:",null,"If you want to have a different Bit Rate for the camera stream you can enter it here and it will overwrite the default setting in the Typical Bit Rate"]
["Step 6:",null,"Select here how much motion in the camera view is expected during a whole day. "]
[null,null,"● PTZ camera continuous moving 100%"]
[null,null,"● Camera with view on a street with traffic approx. 80%-90%"]
[null,null,"● Camera in office 40%-60%"]

{"sheet":"Source","index":1,"n_rows":169,"n_cols":23,"rows_kept":169,"cut":false,"hidden":true,"merged":[[161,5,168,5],[151,5,160,5],[0,1,0,2],[37,5,42,5],[43,5,62,5],[145,5,150,5],[63,5,144,5]]}
[null,"UNIT TYPE",null,"MANUFACTURER",null,"MANUFACTURER","MODEL","Resolution","Res_FPS","ch_capacity","Frame Rate"]
[null,"_8_Channel","_16_Channel","TruVision",null,"TruVision","_TruVision_Gen2_5.0_Mpx","2560×1920","_TruVision_Gen2_5.0_Mpx2560×1920",4,6,4,2,1]
[null,2,2,"Acti",null,null,"_TruVision_Gen2_5.0_Mpx","QXGA(2048×1536)","_TruVision_Gen2_5.0_MpxQXGA(2048×1536)",4,12,10,8,6,4,2,1]
[null,4,4,"ARECONT",null,null,"_TruVision_Gen2_5.0_Mpx","1080P(1920×1080)","_TruVision_Gen2_5.0_Mpx1080P(1920×1080)",4,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,6,6,"AXIS",null,null,"_TruVision_Gen2_5.0_Mpx","UXGA(1600×1200)","_TruVision_Gen2_5.0_MpxUXGA(1600×1200)",4,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,8,8,"CamPlus2_Ip",null,null,"_TruVision_Gen2_5.0_Mpx","1600×912","_TruVision_Gen2_5.0_Mpx1600×912",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,10,10,"Panasonic",null,null,"_TruVision_Gen2_5.0_Mpx","960P(1280×960)","_TruVision_Gen2_5.0_Mpx960P(1280×960)",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,12,12,"UltraView",null,null,"_TruVision_Gen2_5.0_Mpx","720P(1280×720)","_TruVision_Gen2_5.0_Mpx720P(1280×720)",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,14,14,null,null,null,"_TruVision_Gen2_3.0_Mpx","QXGA(2048×1536)","_TruVision_Gen2_3.0_MpxQXGA(2048×1536)",4,12,10,8,6,4,2,1]
[null,16,16,null,null,null,"_TruVision_Gen2_3.0_Mpx","1080P(1920×1080)","_TruVision_Gen2_3.0_Mpx1080P(1920×1080)",4,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","UXGA(1600×1200)","_TruVision_Gen2_3.0_MpxUXGA(1600×1200)",4,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","1600×912","_TruVision_Gen2_3.0_Mpx1600×912",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","960P(1280×960)","_TruVision_Gen2_3.0_Mpx960P(1280×960)",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","720P(1280×720)","_TruVision_Gen2_3.0_Mpx720P(1280×720)",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","VGA(640×480)","_TruVision_Gen2_3.0_MpxVGA(640×480)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","4CIF(704×576)","_TruVision_Gen2_3.0_Mpx4CIF(704×576)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","2CIF(704×288)","_TruVision_Gen2_3.0_Mpx2CIF(704×288)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","CIF(352×288)","_TruVision_Gen2_3.0_MpxCIF(352×288)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_3.0_Mpx","QCIF(176×144)","_TruVision_Gen2_3.0_MpxQCIF(176×144)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","UXGA(1600×1200)","_TruVision_Gen2_2.0_MpxUXGA(1600×1200)",4,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","1600×912","_TruVision_Gen2_2.0_Mpx1600×912",2,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","960P(1280×960)","_TruVision_Gen2_2.0_Mpx960P(1280×960)",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","720P(1280×720)","_TruVision_Gen2_2.0_Mpx720P(1280×720)",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","VGA(640×480)","_TruVision_Gen2_2.0_MpxVGA(640×480)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","4CIF(704×576)","_TruVision_Gen2_2.0_Mpx4CIF(704×576)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","2CIF(704×288)","_TruVision_Gen2_2.0_Mpx2CIF(704×288)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","CIF(352×288)","_TruVision_Gen2_2.0_MpxCIF(352×288)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_2.0_Mpx","QCIF(176×144)","_TruVision_Gen2_2.0_MpxQCIF(176×144)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_1.3_Mpx","HD720P ","_TruVision_Gen2_1.3_MpxHD720P ",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_1.3_Mpx","VGA(640×480)","_TruVision_Gen2_1.3_MpxVGA(640×480)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_SD","VGA(640×480)","_TruVision_Gen2_SDVGA(640×480)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen2_SD","4CIF(704×576)","_TruVision_Gen2_SD4CIF(704×576)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen1_2.0_Mpx","UXGA(1600×1200)","_TruVision_Gen1_2.0_MpxUXGA(1600×1200)",4,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen1_2.0_Mpx","HD720P","_TruVision_Gen1_2.0_MpxHD720P",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen1_2.0_Mpx","VGA(640×480)","_TruVision_Gen1_2.0_MpxVGA(640×480)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen1_1.3_Mpx","HD720P ","_TruVision_Gen1_1.3_MpxHD720P ",2,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,null,"_TruVision_Gen1_1.3_Mpx","VGA(640×480)","_TruVision_Gen1_1.3_MpxVGA(640×480)",1,25,22,20,18,16,15,12,10,8,6,4,2,1]
[null,null,null,null,null,"Acti","_TCM4301_TCM5611_TCM7411","SXGA(1280x1024)","_TCM4301_TCM5611_TCM7411SXGA(1280x1024)",2,18,9,6,4,3,2,1]
[null,null,null,null,null,null,"_TCM4301_TCM5611_TCM7411","720P(1280×720)","_TCM4301_TCM5611_TCM7411720P(1280×720)",2,24,13,8,6,5,4,3,2,1]
[null,null,null,null,null,null,"_TCM4301_TCM5611_TCM7411","VGA(640×480) ","_TCM4301_TCM5611_TCM7411VGA(640×480) ",1,25,15,10,6,5,4,3,2,1]
[null,null,null,null,null,null,"_TCM5311","960P(1280×960)","_TCM5311960P(1280×960)","2",15,7,5,3,2,1]
[null,null,null,null,null,null,"_TCM5311","720P(1280×720) ","_TCM5311720P(1280×720) ",2,24,15,10,8,6,5,4,3,2,1]
[null,null,null,null,null,null,"_TCM5311","VGA(640×480)  ","_TCM5311VGA(640×480)  ",1,25,15,10,8,6,5,4,3,2,1]
[null,null,null,null,null,"ARECONT","_AV1305_AV1315_AV1355","SXGA(1280x1024) ","_AV1305_AV1315_AV1355SXGA(1280x1024) ",2,25,15,10,5,1]
[null,null,null,null,null,null,"_AV1305_AV1315_AV1355","XGA(1024x768)","_AV1305_AV1315_AV1355XGA(1024x768)",2,25,15,10,5,1]
[null,null,null,null,null,null,"_AV1305_AV1315_AV1355","VGA(640×480)   ","_AV1305_AV1315_AV1355VGA(640×480)   ",1,25,15,10,5,1]
[null,null,null,null,null,null,"_AV2105DN_AV2155","UXGA(1600×1200) ","_AV2105DN_AV2155UXGA(1600×1200) ",4,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2105DN_AV2155","SXGA(1280x1024)  ","_AV2105DN_AV2155SXGA(1280x1024)  ",2,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2105DN_AV2155","XGA(1024x768) ","_AV2105DN_AV2155XGA(1024x768) ",2,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2105DN_AV2155","VGA(640×480)    ","_AV2105DN_AV2155VGA(640×480)    ",1,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2805DN_AV2815","1080P(1920×1080)","_AV2805DN_AV28151080P(1920×1080)",4,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2805DN_AV2815","UXGA(1600×1200)  ","_AV2805DN_AV2815UXGA(1600×1200)  ",4,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2805DN_AV2815","SXGA(1280x1024)  ","_AV2805DN_AV2815SXGA(1280x1024)  ",2,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2805DN_AV2815","XGA(1024x768) ","_AV2805DN_AV2815XGA(1024x768) ",2,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV2805DN_AV2815","VGA(640×480)    ","_AV2805DN_AV2815VGA(640×480)    ",1,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV3105_AV3155","QXGA(2048×1536)","_AV3105_AV3155QXGA(2048×1536)",4,15,10,5,1]
[null,null,null,null,null,null,"_AV3105_AV3155","UXGA(1600×1200)   ","_AV3105_AV3155UXGA(1600×1200)   ",4,24,15,10,5,1]
[null,null,null,null,null,null,"_AV3105_AV3155","SXGA(1280x1024)  ","_AV3105_AV3155SXGA(1280x1024)  ",2,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV3105_AV3155","VGA(640×480)    ","_AV3105_AV3155VGA(640×480)    ",1,25,24,15,10,5,1]
[null,null,null,null,null,null,"_AV5105_AV5155","2560×1920","_AV5105_AV51552560×1920",4,15,10,5,1]
[null,null,null,null,null,null,"_AV5105_AV5155","1080P(1920×1080) ","_AV5105_AV51551080P(1920×1080) ",4,25,20,15,9,5,1]
[null,null,null,null,null,null,"_AV5105_AV5155","SXGA(1280x1024)   ","_AV5105_AV5155SXGA(1280x1024)   ",2,25,20,15,9,5,1]
[null,null,null,null,null,null,"_AV5105_AV5155","VGA(640×480)    ","_AV5105_AV5155VGA(640×480)    ",1,25,24,15,10,5,1]
[null,null,null,null,null,"AXIS","_216MFD_216MFD-V ","SXGA(1280x1024)    ","_216MFD_216MFD-V SXGA(1280x1024)    ",2,8,5,1]
[null,null,null,null,null,null,"_216MFD_216MFD-V ","720P(1280×720)  ","_216MFD_216MFD-V 720P(1280×720)  ",2,13,10,8,5,1]
[null,null,null,null,null,null,"_216MFD_216MFD-V ","XGA(1024x768)  ","_216MFD_216MFD-V XGA(1024x768)  ",2,13,10,8,5,1]
[null,null,null,null,null,null,"_216MFD_216MFD-V ","VGA(640×480)       ","_216MFD_216MFD-V VGA(640×480)       ",1,25,20,13,10,8,5,1]
[null,null,null,null,null,null,"_M1114 ","1280x800","_M1114 1280x800",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M1114 ","XGA(1024x768)   ","_M1114 XGA(1024x768)   ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M1114 ","720P(1280×720)   ","_M1114 720P(1280×720)   ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M1114 ","SVGA","_M1114 SVGA",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M1114 ","VGA(640×480)        ","_M1114 VGA(640×480)        ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M1114 ","QVGA(320x240)","_M1114 QVGA(320x240)",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M1114 ","QCIF(176×144) ","_M1114 QCIF(176×144) ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3011","VGA(640×480)        ","_M3011VGA(640×480)        ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3011","QVGA(320x240)","_M3011QVGA(320x240)",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3011","QCIF(176×144) ","_M3011QCIF(176×144) ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014 ","1280x800 ","_M3014 1280x800 ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014 ","XGA(1024x768)   ","_M3014 XGA(1024x768)   ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014 ","720P(1280×720)    ","_M3014 720P(1280×720)    ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014 ","SVGA","_M3014 SVGA",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014","VGA(640×480)        ","_M3014VGA(640×480)        ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014","QVGA(320x240)","_M3014QVGA(320x240)",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014","QCIF(176×144) ","_M3014QCIF(176×144) ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_M3014_ONVIF","720P(1280×720)        ","_M3014_ONVIF720P(1280×720)        ",2,24,23,22,6]
[null,null,null,null,null,null,"_M3014_ONVIF","D1(720x576)","_M3014_ONVIFD1(720x576)",1,24,23,22,6]
[null,null,null,null,null,null,"_M3014_ONVIF","4CIF(704×576)  ","_M3014_ONVIF4CIF(704×576)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_M3014_ONVIF","VGA(640×480)     ","_M3014_ONVIFVGA(640×480)     ",1,24,23,22,6]
[null,null,null,null,null,null,"_M3014_ONVIF","2CIF(704×288) ","_M3014_ONVIF2CIF(704×288) ",1,24,23,22,6]
[null,null,null,null,null,null,"_P1346E","QXGA(2048×1536)","_P1346EQXGA(2048×1536)",4,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E","1080P(1920×1080)  ","_P1346E1080P(1920×1080)  ",4,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E","720P(1280×720)     ","_P1346E720P(1280×720)     ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E","XGA(1024x768)   ","_P1346EXGA(1024x768)   ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E","SVGA","_P1346ESVGA",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E","VGA(640×480)        ","_P1346EVGA(640×480)        ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E","QVGA(320x240)","_P1346EQVGA(320x240)",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E","QCIF(176×144) ","_P1346EQCIF(176×144) ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P1346E_ONVIF","720P(1280×720)        ","_P1346E_ONVIF720P(1280×720)        ",2,24,23,22,6]
[null,null,null,null,null,null,"_P1346E_ONVIF","D1(720x576)","_P1346E_ONVIFD1(720x576)",1,24,23,22,6]
[null,null,null,null,null,null,"_P1346E_ONVIF","4CIF(704×576)  ","_P1346E_ONVIF4CIF(704×576)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_P1346E_ONVIF","VGA(640×480)     ","_P1346E_ONVIFVGA(640×480)     ",1,24,23,22,6]
[null,null,null,null,null,null,"_P1346E_ONVIF","2CIF(704×288) ","_P1346E_ONVIF2CIF(704×288) ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3301","VGA(640×480)        ","_P3301VGA(640×480)        ",1,30,20,15,10,5,1]
[null,null,null,null,null,null,"_P3301","QVGA(320x240)","_P3301QVGA(320x240)",1,30,20,15,10,5,1]
[null,null,null,null,null,null,"_P3301","QCIF(176×144) ","_P3301QCIF(176×144) ",1,30,20,15,10,5,1]
[null,null,null,null,null,null,"_P3301_ONVIF","D1(720x576)","_P3301_ONVIFD1(720x576)",1,24,23,22,6]
[null,null,null,null,null,null,"_P3301_ONVIF","4CIF(704×576)  ","_P3301_ONVIF4CIF(704×576)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3301_ONVIF","VGA(640×480)     ","_P3301_ONVIFVGA(640×480)     ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3301_ONVIF","2CIF(704×288) ","_P3301_ONVIF2CIF(704×288) ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3301_ONVIF","1/2VGA(480x320)","_P3301_ONVIF1/2VGA(480x320)",1,24,23,22,6]
[null,null,null,null,null,null,"_P3301_ONVIF","QCIF(176×144)  ","_P3301_ONVIFQCIF(176×144)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3304 ","1280x800  ","_P3304 1280x800  ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3304 ","XGA(1024x768)   ","_P3304 XGA(1024x768)   ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3304","720P(1280×720)      ","_P3304720P(1280×720)      ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3304","SVGA","_P3304SVGA",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3304","VGA(640×480)        ","_P3304VGA(640×480)        ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3304","QVGA(320x240)","_P3304QVGA(320x240)",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3304","QCIF(176×144) ","_P3304QCIF(176×144) ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3304_ONVIF","720P(1280×720)        ","_P3304_ONVIF720P(1280×720)        ",2,24,23,22,6]
[null,null,null,null,null,null,"_P3304_ONVIF","D1(720x576)","_P3304_ONVIFD1(720x576)",1,24,23,22,6]
[null,null,null,null,null,null,"_P3304_ONVIF","4CIF(704×576)  ","_P3304_ONVIF4CIF(704×576)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3304_ONVIF","VGA(640×480)     ","_P3304_ONVIFVGA(640×480)     ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3304_ONVIF","2CIF(704×288) ","_P3304_ONVIF2CIF(704×288) ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3343  ","SVGA","_P3343  SVGA",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3343  ","VGA(640×480)        ","_P3343  VGA(640×480)        ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3343  ","QVGA(320x240)","_P3343  QVGA(320x240)",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3343  ","QCIF(176×144) ","_P3343  QCIF(176×144) ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3343_ONVIF","D1(720x576)","_P3343_ONVIFD1(720x576)",1,24,23,22,6]
[null,null,null,null,null,null,"_P3343_ONVIF","4CIF(704×576)  ","_P3343_ONVIF4CIF(704×576)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3343_ONVIF","VGA(640×480)     ","_P3343_ONVIFVGA(640×480)     ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3343_ONVIF","2CIF(704×288) ","_P3343_ONVIF2CIF(704×288) ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3343_ONVIF","1/2VGA(480x320)","_P3343_ONVIF1/2VGA(480x320)",1,24,23,22,6]
[null,null,null,null,null,null,"_P3343_ONVIF","QCIF(176×144)  ","_P3343_ONVIFQCIF(176×144)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3344  ","1280x800   ","_P3344  1280x800   ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3344  ","XGA(1024x768)   ","_P3344  XGA(1024x768)   ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3344  ","720P(1280×720)       ","_P3344  720P(1280×720)       ",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3344  ","SVGA","_P3344  SVGA",2,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3344  ","VGA(640×480)        ","_P3344  VGA(640×480)        ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3344  ","QVGA(320x240)","_P3344  QVGA(320x240)",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3344  ","QCIF(176×144) ","_P3344  QCIF(176×144) ",1,25,20,15,10,5,1]
[null,null,null,null,null,null,"_P3344_ONVIF","720P(1280×720)        ","_P3344_ONVIF720P(1280×720)        ",2,24,23,22,6]
[null,null,null,null,null,null,"_P3344_ONVIF","D1(720x576)","_P3344_ONVIFD1(720x576)",1,24,23,22,6]
[null,null,null,null,null,null,"_P3344_ONVIF","4CIF(704×576)  ","_P3344_ONVIF4CIF(704×576)  ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3344_ONVIF","VGA(640×480)     ","_P3344_ONVIFVGA(640×480)     ",1,24,23,22,6]
[null,null,null,null,null,null,"_P3344_ONVIF","2CIF(704×288) ","_P3344_ONVIF2CIF(704×288) ",1,24,23,22,6]
[null,null,null,null,null,"CamPlus2 Ip","_GEC_IP2D_P","VGA(640×480)         ","_GEC_IP2D_PVGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_GEC_IP2D_P","QVGA(320x240) ","_GEC_IP2D_PQVGA(320x240) ",1,25]
[null,null,null,null,null,null,"_GEC_IP2B_P","VGA(640×480)         ","_GEC_IP2B_PVGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_GEC_IP2B_P","QVGA(320x240) ","_GEC_IP2B_PQVGA(320x240) ",1,25]
[null,null,null,null,null,null,"_GEC_IP2VD_DNP","VGA(640×480)         ","_GEC_IP2VD_DNPVGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_GEC_IP2VD_DNP","QVGA(320x240) ","_GEC_IP2VD_DNPQVGA(320x240) ",1,25]
[null,null,null,null,null,"Panasonic","_NS202APTZ","VGA(640×480)         ","_NS202APTZVGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_NS202APTZ","QVGA(320x240) ","_NS202APTZQVGA(320x240) ",1,25]
[null,null,null,null,null,null,"_NS954PTZ","VGA(640×480)         ","_NS954PTZVGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_NS954PTZ","QVGA(320x240) ","_NS954PTZQVGA(320x240) ",1,25]
[null,null,null,null,null,null,"_WV_NW484s","VGA(640×480)         ","_WV_NW484sVGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_WV_NW484s","QVGA(320x240) ","_WV_NW484sQVGA(320x240) ",1,25]
[null,null,null,null,null,null,"_WV_NF284","VGA(640×480)         ","_WV_NF284VGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_WV_NF284","QVGA(320x240) ","_WV_NF284QVGA(320x240) ",1,25]
[null,null,null,null,null,null,"_WV_NP244","VGA(640×480)         ","_WV_NP244VGA(640×480)         ",1,25]
[null,null,null,null,null,null,"_WV_NP244","QVGA(320x240) ","_WV_NP244QVGA(320x240) ",1,25]
[null,null,null,null,null,"UltraView","_UVD_IP","4CIF(704×576) ","_UVD_IP4CIF(704×576) ",1,25,15,7.5,3.5,2,1]
[null,null,null,null,null,null,"_UVD_IP","2CIF(704×288)   ","_UVD_IP2CIF(704×288)   ",1,25,15,7.5,3.5,2,1]
[null,null,null,null,null,null,"_UVD_IP","CIF(352×288) ","_UVD_IPCIF(352×288) ",1,25,15,7.5,3.5,2,1]
[null,null,null,null,null,null,"_UVD_IP","QCIF(176×144)   ","_UVD_IPQCIF(176×144)   ",1,25,15,7.5,3.5,2,1]
[null,null,null,null,null,null,"_UVE_101","4CIF(704×576) ","_UVE_1014CIF(704×576) ",1,25,15,7.5,3.5,2,1]
[null,null,null,null,null,null,"_UVE_101","2CIF(704×288)   ","_UVE_1012CIF(704×288)   ",1,25,15,7.5,3.5,2,1]
[null,null,null,null,null,null,"_UVE_101","CIF(352×288) ","_UVE_101CIF(352×288) ",1,25,15,7.5,3.5,2,1]
[null,null,null,null,null,null,"_UVE_101","QCIF(176×144)","_UVE_101QCIF(176×144)",1,25,15,7.5,3.5,2,1]

{"sheet":"MODEL","index":2,"n_rows":41,"n_cols":11,"rows_kept":41,"cut":false,"hidden":true,"merged":[[1,0,7,0],[38,0,40,0],[0,1,0,2],[8,0,9,0],[10,0,14,0],[30,0,32,0],[33,0,37,0],[15,0,29,0]]}
["MANUFACTURER","MODEL"]
["TruVision","883/783","_TruVision_Gen2_5.0_Mpx",null,"TruVision","Acti","ARECONT","AXIS","CamPlus2 Ip","Panasonic","UltraView"]
[null,"854/754","_TruVision_Gen2_3.0_Mpx",null,"_TruVision_Gen1_2.0_Mpx","_TCM4301_TCM5611_TCM7411","_AV1305_AV1315_AV1355","_216MFD","_GEC_IP2D_P","_NS202APTZ","_UVC_IP"]
[null,"853/753","_TruVision_Gen2_2.0_Mpx",null,"_TruVision_Gen1_1.3_Mpx","_TCM5311","_AV2105DN_AV2155","_M1114 ","_GEC_IP2B_P","_NS954PTZ","_UVD_IP"]
[null,"863/763","_TruVision_Gen2_1.3_Mpx",null,"_TruVision_Gen2_5.0_Mpx",null,"_AV2805DN_AV2815","_M3011","_GEC_IP2VD_DNP","_WV_NW484s","_UVE_101"]
[null,"833/733","_TruVision_Gen2_VGA",null,"_TruVision_Gen2_3.0_Mpx",null,"_AV3105_AV3155","_M3014 ",null,"_WV_NF284"]
[null,"852/752","_TruVision_Gen1_2.0_Mpx",null,"_TruVision_Gen2_2.0_Mpx",null,"_AV5105_AV5155","_M3014_ONVIF",null,"_WV_NP244"]
[null,"862/762","_TruVision_Gen1_1.3_Mpx",null,"_TruVision_Gen2_1.3_Mpx",null,null,"_P1346E"]
["Acti","TCM4301\nTCM5611\nTCM7411","_TCM4301_TCM5611_TCM7411",null,"_TruVision_Gen2_SD",null,null,"_P1346E_ONVIF"]
[null,"TCM5311","_TCM5311",null,null,null,null,"_P3301"]
["ARECONT","AV1305\nAV1315\nAV1355","_AV1305_AV1315_AV1355",null,null,null,null,"_P3301_ONVIF"]
[null,"AV2105DN\nAV2155","_AV2105DN_AV2155",null,null,null,null,"_P3304 "]
[null,"AV2805DN\nAV2815","_AV2805DN_AV2815",null,null,null,null,"_P3304_ONVIF"]
[null,"AV3105\nAV3155","_AV3105_AV3155",null,null,null,null,"_P3343  "]
[null,"AV5105\nAV5155","_AV5105_AV5155",null,null,null,null,"_P3343_ONVIF"]
["AXIS","216MFD","_216MFD",null,null,null,null,"_P3344  "]
[null,"M1114 ","_M1114 ",null,null,null,null,"_P3344_ONVIF"]
[null,"M3011","_M3011"]
[null,"M3014 ","_M3014 "]
[null,"M3014_ONVIF","_M3014_ONVIF"]
[null,"P1346E","_P1346E"]
[null,"P1346E_ONVIF","_P1346E_ONVIF"]
[null,"P3301","_P3301"]
[null,"P3301_ONVIF","_P3301_ONVIF"]
[null,"P3304 ","_P3304 "]
[null,"P3304_ONVIF","_P3304_ONVIF"]
[null,"P3343  ","_P3343  "]
[null,"P3343_ONVIF","_P3343_ONVIF"]
[null,"P3344  ","_P3344  "]
[null,"P3344_ONVIF","_P3344_ONVIF"]
["CamPlus2 Ip","GEC-IP2D-P","_GEC_IP2D_P"]
[null,"GEC-IP2B-P","_GEC_IP2B_P"]
[null,"GEC-IP2VD-DNP","_GEC_IP2VD_DNP"]
["Panasonic","NS202APTZ","_NS202APTZ"]
[null,"NS954PTZ","_NS954PTZ"]
[null,"WV-NW484s","_WV_NW484s"]
[null,"WV-NF284","_WV_NF284"]
[null,"WV-NP244","_WV_NP244"]
["UltraView","UVC-IP","_UVC_IP"]
[null,"UVD-IP","_UVD_IP"]
[null,"UVE-101","_UVE_101"]

{"sheet":"BITRATE","index":3,"n_rows":58,"n_cols":3,"rows_kept":58,"cut":false,"hidden":true,"merged":[[49,1,56,1],[1,1,22,1],[23,1,29,1],[30,1,34,1],[35,1,39,1],[40,1,48,1]]}
[null,"MANUFACTURER","Custom(32-8192Kbps)"]
[null,"TruVision",2048]
[null,null,1792]
[null,null,1536]
[null,null,1280]
[null,null,1024]
[null,null,896]
[null,null,768]
[null,null,640]
[null,null,512]
[null,null,448]
[null,null,384]
[null,null,320]
[null,null,256]
[null,null,244]
[null,null,192]
[null,null,160]
[null,null,128]
[null,null,96]
[null,null,80]
[null,null,64]
[null,null,48]
[null,null,32]
[null,"Acti",6144]
[null,null,5120]
[null,null,4096]
[null,null,3072]
[null,null,2048]
[null,null,1024]
[null,null,512]
[null,"ARECONT",4096]
[null,null,3072]
[null,null,2048]
[null,null,1024]
[null,null,512]
[null,"AXIS",3072]
[null,null,2048]
[null,null,1536]
[null,null,1024]
[null,null,512]
[null,"CamPlus2 Ip",4096]
[null,null,3072]
[null,null,2048]
[null,null,1536]
[null,null,1024]
[null,null,512]
[null,null,256]
[null,null,128]
[null,null,64]
[null,"Panasonic",4096]
[null,null,3072]
[null,null,2048]
[null,null,1024]
[null,null,512]
[null,null,256]
[null,null,128]
[null,null,64]
[null,"UltraView",2048]

{"sheet":"proposed","index":4,"n_rows":36,"n_cols":28,"rows_kept":36,"cut":false,"hidden":true,"merged":[[0,1,0,27]]}
[null,"Common compression resolution/frame rate proposed table(approximate)"]
[null,"Frame rate（fps）\nResolution",25,24,23,22,20,18,16,15,13,12,10,9,8,7.5,7,6,5,4,3.5,3,2,1,"1/2","1/4","1/8","1/16"]
["2560×1920","2560×1920","8192","8192","8192","8192","8192","8192","8192","8192","8192","8192","8192","8192","8192","8192","8192","7168","5120","5120","5120","5120","3072","2048","1024","512","256","128"]
["QXGA(2048×1536)","QXGA(2048×1536)","8192","8192","8192","8192","8192","8192","8192","7168","7168","7168","6144","6144","5120","5120","5120","5120","4096","4096","4096","4096","3072","1536","768","348","192","96"]
["1080P(1920×1080)","1080P(1920×1080)","8192","8192","8192","6144","5120","5120","5120","4096","4096","4096","4096","4096","3072","3072","3072","3072","2048","2048","2048","2048","1792","1024","512","256","128","64"]
["UXGA(1600×1200)","UXGA(1600×1200)","8192","8192","8192","6144","5120","5120","5120","4096","4096","4096","4096","4096","3072","3072","3072","3072","2048","2048","2048","2048","1792","1024","512","256","128","64"]
["1600×912","1600×912",7000,7000,7000,"4096","3072","3072","3072","3072","3072","2048","2048","2048","2048","2048","2048","1792","1536","1536","1536","1536","1024","640","320","180","90","45"]
["SXGA(1280x1024)","SXGA(1280x1024)",7000,7000,7000,"4096","3072","3072","3072","2048","2048","2048","2048","2048","2048","2048","2048","1024","1024","1024","1024","1024","1024","512","320","180","90","45"]
["1280×800","1280x800",6000,6000,6000,"3072","3072","3072","3072","2048","2048","2048","2048","2048","1792","1792","1792","1536","1280","1280","1280","1280","896","512","256","128","64","32"]
["1280×960","960P(1280×960)",6000,6000,6000,"3072","3072","3072","3072","2048","2048","2048","2048","2048","1792","1792","1792","1536","1280","1280","1280","1280","896","512","256","128","64","32"]
["HD720P","HD720P",6000,6000,6000,"3072","2048","2048","2048","1792","1792","1792","1536","1536","1536","1536","1536","1536","1280","1280","1280","1280","768","512","256","128","64","32"]
["720P(1280×720)","720P(1280×720)",6000,6000,6000,"3072","2048","2048","2048","1792","1792","1792","1536","1536","1536","1536","1536","1536","1280","1280","1280","1280","768","512","256","128","64","32"]
["XGA(1024x768)","XGA(1024x768)",6000,6000,6000,"3072","2048","2048","2048","2048","2048","1024","1024","1024","1024","1024","1024","1024","1024","1024","1024","1024","512","512","256","128","64","32"]
["VGA(640×480)","VGA(640×480)","1536","1536","1536","1280","1280","1024","1024","896","896","768","640","640","640","640","640","512","512","448","448","448","256","160","80","40","32","32"]
["D1(720x576)","D1(720x576)","2048","2048","2048","1536","1280","1280","1280","1024","1024","896","768","768","640","640","640","640","512","512","512","512","320","160","80","64","48","32"]
["4CIF(704×576)","4CIF(704×576)","2048","2048","2048","1536","1280","1280","1280","1024","1024","896","768","768","640","640","640","640","512","512","512","512","320","160","80","64","48","32"]
["DCIF(528x284)","DCIF(528x284)","1024","1024","1024","768","640","512","512","512","512","448","384","384","320","320","320","320","256","256","256","256","160","96","48","48","32","32"]
["2CIF(704×288)","2CIF(704×288)","1024","1024","1024","768","640","512","512","512","512","448","384","384","320","320","320","320","256","256","256","256","160","96","48","48","32","32"]
["1/2VGA(480x320)","1/2VGA(480x320)","1024","1024","1024","768","640","512","512","512","512","448","384","384","320","320","320","320","256","256","256","256","160","96","48","48","32","32"]
["CIF(352×288)","CIF(352×288)","768","768","768","512","512","384","384","320","320","320","256","256","192","192","192","160","160","160","160","160","96","64","32","32","32","32"]
["QVGA(320x240)","QVGA(320x240)","768","768","768","512","512","512","512","512","512","512","256","256","256","256","256","128","128","128","128","128","64","64","32","32","32","32"]
["QCIF(176×144)","QCIF(176×144)","224","224","224","160","128","128","128","128","128","96","96","96","80","80","80","80","80","64","64","64","48","32","32","32","32","32"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"MID(O3, 1, LEN(O3)-4)","v":""},"","","","","","","",{"$f":"MID(W3, 1, LEN(W3)-4)","v":""},"","",{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,{"$f":"MID(F4, 1, LEN(F4)-4)","v":""},"","","","","","","","","","","","","","","","",{"$f":"MID(W4, 1, LEN(W4)-4)","v":""},"",{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,{"$f":"MID(F5, 1, LEN(F5)-4)","v":""},"","","","","","","","","","","","","","","","",{"$f":"MID(W5, 1, LEN(W5)-4)","v":""},"",{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"","","","","","","","","","","","","","","","","",{"$f":"MID(W6, 1, LEN(W6)-4)","v":""},"",{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"","","","","","","","","","","","","","","","","",{"$f":"MID(W7, 1, LEN(W7)-4)","v":""},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"","","","","","","","","","","","","","","","","",{"$f":"MID(W8, 1, LEN(W8)-4)","v":""},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"","","","","","","","","","","","","","","","","",{"$f":"MID(W9, 1, LEN(W9)-4)","v":{"$error":"#VALUE!"}},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"","","","","","","","","","","","","","","","","",{"$f":"MID(W10, 1, LEN(W10)-4)","v":{"$error":"#VALUE!"}},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"","","","","","","","","","","","","","","","","",{"$f":"MID(W11, 1, LEN(W11)-4)","v":{"$error":"#VALUE!"}},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"","","","","","","","","","","","","","","","","",{"$f":"MID(W12, 1, LEN(W12)-4)","v":{"$error":"#VALUE!"}},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,"",{"$f":"MID(G13, 1, LEN(G13)-4)","v":""},"","","","","","","","","","","","","","","",{"$f":"MID(W13, 1, LEN(W13)-4)","v":{"$error":"#VALUE!"}},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
[null,null,null,null,null,""]
[null,null,null,null,null,""]